{"id":50836,"date":"2026-05-06T16:01:18","date_gmt":"2026-05-06T22:01:18","guid":{"rendered":"https:\/\/themesh.art\/?post_type=venues&#038;p=50836"},"modified":"2026-05-06T16:01:29","modified_gmt":"2026-05-06T22:01:29","slug":"centro-cultural-recoleta-2","status":"publish","type":"venues","link":"https:\/\/themesh.art\/en\/venues\/centro-cultural-recoleta-2\/","title":{"rendered":"Centro Cultural Recoleta"},"content":{"rendered":"<p>El Centro Cultural Recoleta es, desde comienzos de los a\u00f1os 80, un espacio emblem\u00e1tico de la vida de la Ciudad de Buenos Aires. Proyectado en un predio con 300 a\u00f1os de historia, su programaci\u00f3n conecta tradici\u00f3n y vanguardia, y es visitado por m\u00e1s de medio mill\u00f3n de personas al a\u00f1o.<\/p>\n<p>En sus 17 mil metros cuadrados conviven las artes visuales y las esc\u00e9nicas, el cine, la literatura y las m\u00fasicas y danzas urbanas. Alberga muestras de artistas nacionales y extranjeros, cuenta con patios y espacios de permanencia que funcionan como refugios urbanos y dispone de salas de baile y entrenamiento.<\/p>\n<p>En el CCR funciona adem\u00e1s un reconocido laboratorio de investigaci\u00f3n musical, un centro de investigaci\u00f3n y publicaciones y una residencia para artistas. Algunos lugares son ya m\u00edticos, como la Capilla (donde se realizan shows musicales y obras de teatro) y las salas Cronopios, J-C y Villa Villa.<\/p>\n<p>Experimentaci\u00f3n, creaci\u00f3n, participaci\u00f3n, memoria y convivencia son algunos de los valores que determinan el cruce de las actividades que el CCR propone, muchas de ellas de forma gratuita para la comunidad. Exhibiciones de artes visuales, dibujo y fotograf\u00eda funcionan de manera simult\u00e1nea y sincr\u00f3nica con una oferta m\u00faltiple de talleres, festivales, recitales y proyecciones de cine.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Centro Cultural Recoleta es, desde comienzos de los a\u00f1os 80, un espacio emblem\u00e1tico de la vida de la Ciudad de Buenos Aires. Proyectado en un predio con 300 a\u00f1os de historia, su programaci\u00f3n conecta tradici\u00f3n y vanguardia, y es visitado por m\u00e1s de medio mill\u00f3n de personas al a\u00f1o.<\/p>","protected":false},"author":40,"featured_media":50837,"template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"b9e7b6d15e5b3662afcbbd8db24d8232_lat":"-34.5864788","b9e7b6d15e5b3662afcbbd8db24d8232_lng":"-58.3917134","featured_venue":"false","robot_status":"","direccion_google_maps":"Jun\u00edn 1930, C1113AAX Cdad. Aut\u00f3noma de Buenos Aires, Argentina","membership":"Undefined","category":""},"etiquetas-del-venue":[1576,2353,1585,1568,1621],"categoria-del-venue":[1537],"ubicacion-del-venue":[2030,2467],"class_list":["post-50836","venues","type-venues","status-publish","has-post-thumbnail","hentry","etiquetas-del-venue-arte-contemporaneo","etiquetas-del-venue-arte-contemporaneo-artes-visuales-2","etiquetas-del-venue-artes-visuales","etiquetas-del-venue-exposiciones","etiquetas-del-venue-objeto","categoria-del-venue-centro-cultural","ubicacion-del-venue-argentina","ubicacion-del-venue-buenos-aires"],"_links":{"self":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/venues\/50836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/venues"}],"about":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/types\/venues"}],"author":[{"embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/users\/40"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/media\/50837"}],"wp:attachment":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/media?parent=50836"}],"wp:term":[{"taxonomy":"etiquetas-del-venue","embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/etiquetas-del-venue?post=50836"},{"taxonomy":"categoria-del-venue","embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/categoria-del-venue?post=50836"},{"taxonomy":"ubicacion-del-venue","embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/ubicacion-del-venue?post=50836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}