{"id":50669,"date":"2026-05-04T23:32:23","date_gmt":"2026-05-05T05:32:23","guid":{"rendered":"https:\/\/themesh.art\/venues\/kinetic-ai\/"},"modified":"2026-05-04T23:41:37","modified_gmt":"2026-05-05T05:41:37","slug":"kinetic-ai","status":"publish","type":"venues","link":"https:\/\/themesh.art\/en\/venues\/kinetic-ai\/","title":{"rendered":"Kinetic AI"},"content":{"rendered":"<p>Desde <a href=\"https:\/\/www.linkedin.com\/company\/kinetic4i\/\" target=\"_blank\" style=\"color: inherit\">Kinetic AI<\/a>, queremos explorar c\u00f3mo unir la tecnolog\u00eda generativa y la inclusi\u00f3n para crear experiencias \u00fanicas con impacto social y art\u00edstico. Estamos investigando c\u00f3mo usar la tecnolog\u00eda generativa para hacer abordar temas de inclusi\u00f3n, contenido, dise\u00f1o de obra art\u00edstica y educaci\u00f3n sobre nuevos medios.<\/p>","protected":false},"excerpt":{"rendered":"<p>Laboratorio de Experimentaci\u00f3n KIn\u00e9tica Digital<\/p>","protected":false},"author":232,"featured_media":50670,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"b9e7b6d15e5b3662afcbbd8db24d8232_lat":"19.3207722","b9e7b6d15e5b3662afcbbd8db24d8232_lng":"-99.1514678","featured_venue":"","robot_status":"","direccion_google_maps":"Cdmx","membership":"","category":""},"etiquetas-del-venue":[2453,2405,1611,2536,1579,1568,1587,1594,1591,2552,2454,1574],"categoria-del-venue":[1542,2288,1564,2055,1540,2227],"ubicacion-del-venue":[1209],"class_list":["post-50669","venues","type-venues","status-publish","has-post-thumbnail","hentry","etiquetas-del-venue-animacion","etiquetas-del-venue-arte-digital","etiquetas-del-venue-cine","etiquetas-del-venue-curaduria","etiquetas-del-venue-danza","etiquetas-del-venue-exposiciones","etiquetas-del-venue-media","etiquetas-del-venue-online","etiquetas-del-venue-performance","etiquetas-del-venue-servicios-creativos","etiquetas-del-venue-video","etiquetas-del-venue-workshops","categoria-del-venue-colectivo","categoria-del-venue-danza","categoria-del-venue-diseno","categoria-del-venue-espacio-independiente","categoria-del-venue-online","categoria-del-venue-servicios-culturales","ubicacion-del-venue-cdmx"],"_links":{"self":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/venues\/50669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/venues"}],"about":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/types\/venues"}],"author":[{"embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/users\/232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/media\/50670"}],"wp:attachment":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/media?parent=50669"}],"wp:term":[{"taxonomy":"etiquetas-del-venue","embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/etiquetas-del-venue?post=50669"},{"taxonomy":"categoria-del-venue","embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/categoria-del-venue?post=50669"},{"taxonomy":"ubicacion-del-venue","embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/ubicacion-del-venue?post=50669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}