{"id":39106,"date":"2025-12-15T13:35:06","date_gmt":"2025-12-15T19:35:06","guid":{"rendered":"https:\/\/themesh.art\/venues\/tanya-bonakdar-gallery\/"},"modified":"2025-12-15T13:47:05","modified_gmt":"2025-12-15T19:47:05","slug":"tanya-bonakdar-gallery","status":"publish","type":"venues","link":"https:\/\/themesh.art\/en\/venues\/tanya-bonakdar-gallery\/","title":{"rendered":"Tanya Bonakdar Gallery"},"content":{"rendered":"<p>Tanya Bonakdar trabaja con artistas contempor\u00e1neos de alto nivel en instalaci\u00f3n, escultura, video y nuevas tecnolog\u00edas, con un enfoque en proyectos de gran escala. Su programa dialoga con instituciones y produce obras complejas.<\/p>\n<p>https:\/\/www.tanyabonakdargallery.com\/<\/p>","protected":false},"excerpt":{"rendered":"<p>Contempor\u00e1neo internacional con proyectos ambiciosos.<\/p>","protected":false},"author":1,"featured_media":38749,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"b9e7b6d15e5b3662afcbbd8db24d8232_lat":"40.7470772","b9e7b6d15e5b3662afcbbd8db24d8232_lng":"-74.0061877","featured_venue":"","robot_status":"","direccion_google_maps":"521 W 21st St, New York, NY 10011, USA","membership":"","category":""},"etiquetas-del-venue":[1585],"categoria-del-venue":[1531],"ubicacion-del-venue":[1246,1241],"class_list":["post-39106","venues","type-venues","status-publish","has-post-thumbnail","hentry","etiquetas-del-venue-artes-visuales","categoria-del-venue-galeria","ubicacion-del-venue-new-york","ubicacion-del-venue-usa"],"_links":{"self":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/venues\/39106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/venues"}],"about":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/types\/venues"}],"author":[{"embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/media\/38749"}],"wp:attachment":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/media?parent=39106"}],"wp:term":[{"taxonomy":"etiquetas-del-venue","embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/etiquetas-del-venue?post=39106"},{"taxonomy":"categoria-del-venue","embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/categoria-del-venue?post=39106"},{"taxonomy":"ubicacion-del-venue","embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/ubicacion-del-venue?post=39106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}