{"id":38556,"date":"2025-12-05T23:23:00","date_gmt":"2025-12-06T05:23:00","guid":{"rendered":"https:\/\/themesh.art\/?post_type=venues&#038;p=38556"},"modified":"2025-12-05T23:46:35","modified_gmt":"2025-12-06T05:46:35","slug":"akademie-der-bildenden-kunste-munchen","status":"publish","type":"venues","link":"https:\/\/themesh.art\/en\/venues\/akademie-der-bildenden-kunste-munchen\/","title":{"rendered":"Akademie der Bildenden K\u00fcnste M\u00fcnchen"},"content":{"rendered":"<p>Akademie der Bildenden K\u00fcnste M\u00fcnchen (ADBK) es una academia alemana destacada por su \u00e9nfasis en investigaci\u00f3n art\u00edstica, experimentaci\u00f3n y pensamiento conceptual.<\/p>","protected":false},"excerpt":{"rendered":"<p>Akademie der Bildenden K\u00fcnste M\u00fcnchen (ADBK) es una academia alemana destacada por su \u00e9nfasis en investigaci\u00f3n art\u00edstica, experimentaci\u00f3n y pensamiento conceptual.<\/p>","protected":false},"author":1,"featured_media":38580,"template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"b9e7b6d15e5b3662afcbbd8db24d8232_lat":"48.1531313","b9e7b6d15e5b3662afcbbd8db24d8232_lng":"11.5791506","featured_venue":"","robot_status":"","direccion_google_maps":"Akademiestra\u00dfe 2\u20134, 80799 M\u00fcnchen, Germany","membership":"","category":""},"etiquetas-del-venue":[1585,1573,1572,1574],"categoria-del-venue":[1535],"ubicacion-del-venue":[2283,2579],"class_list":["post-38556","venues","type-venues","status-publish","has-post-thumbnail","hentry","etiquetas-del-venue-artes-visuales","etiquetas-del-venue-cursos","etiquetas-del-venue-educacion","etiquetas-del-venue-workshops","categoria-del-venue-educacion","ubicacion-del-venue-alemania","ubicacion-del-venue-munich"],"_links":{"self":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/venues\/38556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/venues"}],"about":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/types\/venues"}],"author":[{"embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/media\/38580"}],"wp:attachment":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/media?parent=38556"}],"wp:term":[{"taxonomy":"etiquetas-del-venue","embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/etiquetas-del-venue?post=38556"},{"taxonomy":"categoria-del-venue","embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/categoria-del-venue?post=38556"},{"taxonomy":"ubicacion-del-venue","embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/ubicacion-del-venue?post=38556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}