{"id":2533,"count":1,"description":"","link":"https:\/\/themesh.art\/en\/ubicacion-del-venue\/tepic\/","name":"Tepic","slug":"tepic","taxonomy":"ubicacion-del-venue","parent":1208,"meta":[],"_links":{"self":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/ubicacion-del-venue\/2533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/ubicacion-del-venue"}],"about":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/taxonomies\/ubicacion-del-venue"}],"up":[{"embeddable":true,"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/ubicacion-del-venue\/1208"}],"wp:post_type":[{"href":"https:\/\/themesh.art\/en\/wp-json\/wp\/v2\/venues?ubicacion-del-venue=2533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}